{"id":9851,"date":"2021-03-23T13:03:29","date_gmt":"2021-03-23T13:03:29","guid":{"rendered":"https:\/\/cstradha.xyz\/do\/?page_id=9851"},"modified":"2025-01-10T20:25:53","modified_gmt":"2025-01-10T20:25:53","slug":"camisas-tipo-columbia-para-empresas","status":"publish","type":"page","link":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/","title":{"rendered":"Camisas tipo columbia para empresas"},"content":{"rendered":"<h1>Camisas tipo columbia para empresas<\/h1>\n<blockquote><p>La comodidad de sus empleados a la hora de trabajar, en especial en ambientes que son muy calurosos e inc\u00f3modos para ejercer las labores, es muy importante, ya que en primer lugar, pensar en la comodidad del empleado para ejercer su trabajo, es s\u00edmbolo de aumento de rendimiento tanto para \u00e9l\/ella, como para la empresa. Una ropa de trabajo que sea muy inc\u00f3moda, no va a permitir que el empleado se desempe\u00f1e con el rendimiento suficiente y que por consiguiente, termine la jornada de trabajo muy cansado, o que no termine el trabajo a tiempo por la afecci\u00f3n de la integridad f\u00edsica, e imaginamos que usted como gerente de recursos humanos de su empresa, no le gustar\u00eda que eso pase. Es por eso, que como pensamos en las necesidades que tienen las empresas en cuanto a prendas de vestir se refiere, que <strong>realizamos la confeccion y venta de camisas tipo columbia para empresas, a buenos precios y con calidad de tela original (tela popl\u00edn), en Santo Domingo, RD<\/strong>, con el objetivo de que usted vista a sus empleados con ropa adecuada para trabajar y elegantes al mismo tiempo.<\/p>\n<p>Disponemos de diferentes y variados <strong>modelos de camisas tipo columbia para empresas<\/strong>, con el objetivo de que usted elija el m\u00e1s adecuado para vestir a sus empleados de acuerdo a su presupuesto y necesidades.<\/p><\/blockquote>\n<p><a href=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9853\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\" alt=\"camisas tipo columbia para empresas\" width=\"1280\" height=\"331\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png 1280w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas-300x78.png 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas-1024x265.png 1024w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas-768x199.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<style>#jtg-9791 .modula-item { border: 3px solid #aaaaaa; }#jtg-9791 .modula-item { border-radius: 5px; }#jtg-9791 .modula-item { box-shadow: #aaaaaa 0px 0px 3px; }#jtg-9791 .modula-item .jtg-social a, .lightbox-socials.jtg-social a{ fill: #ffffff; color: #ffffff }#jtg-9791 .modula-item .jtg-social-expandable a, #jtg-9791 .modula-item .jtg-social-expandable-icons a{ fill: #ffffff; color: #ffffff }#jtg-9791 .modula-item .jtg-social svg, .lightbox-socials.jtg-social svg { height: 16px; width: 16px }#jtg-9791 .modula-item .jtg-social-expandable svg { height: 16px; width: 16px }#jtg-9791 .modula-item .jtg-social-expandable-icons svg { height: 16px; width: 16px }#jtg-9791 .modula-item .jtg-social a:not(:last-child), .lightbox-socials.jtg-social a:not(:last-child) { margin-right: 10px }#jtg-9791 .modula-item .jtg-social-expandable-icons { gap: 10px }#jtg-9791 .modula-item .figc {color:#ffffff;}#jtg-9791 .modula-item .modula-item-content { transform: scale(1); }#jtg-9791 { width:100%;}#jtg-9791 .modula-items .figc p.description { font-size:14px; }#jtg-9791 .modula-items .figc p.description { color:#ffffff;}#jtg-9791.modula-gallery .modula-item > a, #jtg-9791.modula-gallery .modula-item, #jtg-9791.modula-gallery .modula-item-content > a:not(.modula-no-follow) { cursor:zoom-in; } #jtg-9791.modula-gallery .modula-item-content .modula-no-follow { cursor: default; } #jtg-9791.modula-gallery .modula-item, #jtg-9791.modula-gallery .modula-grid-sizer { width: calc(25% - 7.5px) ; } @media (min-width: 768px) and (max-width:992px) { html body #jtg-9791.modula-gallery .modula-item, html body  #jtg-9791.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }@media (max-width: 768px) { html body #jtg-9791.modula-gallery .modula-item, html body  #jtg-9791.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }#jtg-9791 .modula-items{position:relative;}@media screen and (max-width:480px){#jtg-9791 .modula-item .figc .jtg-title {  font-size: 12px; }#jtg-9791 .modula-items .figc p.description { color:#ffffff;font-size:10px; }}<\/style>\n<div  id=\"jtg-9791\" class=\"modula modula-gallery modula-columns\" data-config=\"{&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:&quot;2&quot;,&quot;mobileColumns&quot;:&quot;1&quot;,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:false},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-9791&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;grid_type&quot;:&quot;4&quot;,&quot;rowHeight&quot;:150,&quot;lastRow&quot;:&quot;justify&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t<div class=\"modula-grid-sizer\"> <\/div>\n\t<div  class=\"modula-items grid-gallery\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9805\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9805\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada.jpg\" title=\"camisas columbia manga de mujer manga corta rosada\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada.jpg 564w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-de-mujer-manga-corta-rosada-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga de mujer manga corta rosada<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9806\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9806\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo.jpg\" title=\"camisas columbia manga larga azul cielo\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo.jpg 564w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-azul-cielo-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga larga azul cielo<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9807\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9807\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel.jpg\" title=\"camisas columbia manga larga color pastel\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-pastel-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga larga color pastel<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9802\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9802\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa.jpg\" title=\"camisas columbia manga corta azul turquesa\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-azul-turquesa-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga corta azul turquesa<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9803\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9803\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado.jpg\" title=\"camisas columbia manga corta color morado\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado.jpg 500w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-color-morado-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga corta color morado<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9800\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9800\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal.jpg\" title=\"camisas columbia manga color teal\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-teal-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga color teal<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9798\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9798\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro.jpg\" title=\"camisas columbia manga color caqui claro\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-caqui-claro-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga color caqui claro<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9804\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9804\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre.jpg\" title=\"camisas columbia manga corta roja de hombre\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-corta-roja-de-hombre-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga corta roja de hombre<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9801\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9801\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales.jpg\" title=\"camisas columbia manga con 2 bolsillos normales\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales.jpg 564w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-con-2-bolsillos-normales-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga con 2 bolsillos normales<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9799\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9799\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema.jpg\" title=\"camisas columbia manga color crema\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-color-crema-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga color crema<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9808\" role=\"button\" tabindex=\"0\" rel=\"jtg-9791\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9808\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo.jpg\" title=\"camisas columbia manga larga color verde olivo\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo.jpg 564w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-manga-larga-color-verde-olivo-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia manga larga color verde olivo<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"http:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\",\n\t\t\"url\"     : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n<hr>\n<style>#jtg-9792 .modula-item { border: 3px solid #aaaaaa; }#jtg-9792 .modula-item { border-radius: 5px; }#jtg-9792 .modula-item { box-shadow: #aaaaaa 0px 0px 3px; }#jtg-9792 .modula-item .jtg-social a, .lightbox-socials.jtg-social a{ fill: #ffffff; color: #ffffff }#jtg-9792 .modula-item .jtg-social-expandable a, #jtg-9792 .modula-item .jtg-social-expandable-icons a{ fill: #ffffff; color: #ffffff }#jtg-9792 .modula-item .jtg-social svg, .lightbox-socials.jtg-social svg { height: 16px; width: 16px }#jtg-9792 .modula-item .jtg-social-expandable svg { height: 16px; width: 16px }#jtg-9792 .modula-item .jtg-social-expandable-icons svg { height: 16px; width: 16px }#jtg-9792 .modula-item .jtg-social a:not(:last-child), .lightbox-socials.jtg-social a:not(:last-child) { margin-right: 10px }#jtg-9792 .modula-item .jtg-social-expandable-icons { gap: 10px }#jtg-9792 .modula-item .figc {color:#ffffff;}#jtg-9792 .modula-item .modula-item-content { transform: scale(1); }#jtg-9792 { width:100%;}#jtg-9792 .modula-items .figc p.description { font-size:14px; }#jtg-9792 .modula-items .figc p.description { color:#ffffff;}#jtg-9792.modula-gallery .modula-item > a, #jtg-9792.modula-gallery .modula-item, #jtg-9792.modula-gallery .modula-item-content > a:not(.modula-no-follow) { cursor:zoom-in; } #jtg-9792.modula-gallery .modula-item-content .modula-no-follow { cursor: default; } #jtg-9792.modula-gallery .modula-item, #jtg-9792.modula-gallery .modula-grid-sizer { width: calc(25% - 7.5px) ; } @media (min-width: 768px) and (max-width:992px) { html body #jtg-9792.modula-gallery .modula-item, html body  #jtg-9792.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }@media (max-width: 768px) { html body #jtg-9792.modula-gallery .modula-item, html body  #jtg-9792.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }#jtg-9792 .modula-items{position:relative;}@media screen and (max-width:480px){#jtg-9792 .modula-item .figc .jtg-title {  font-size: 12px; }#jtg-9792 .modula-items .figc p.description { color:#ffffff;font-size:10px; }}<\/style>\n<div  id=\"jtg-9792\" class=\"modula modula-gallery modula-columns\" data-config=\"{&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:&quot;2&quot;,&quot;mobileColumns&quot;:&quot;1&quot;,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:false},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-9792&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;grid_type&quot;:&quot;4&quot;,&quot;rowHeight&quot;:150,&quot;lastRow&quot;:&quot;justify&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t<div class=\"modula-grid-sizer\"> <\/div>\n\t<div  class=\"modula-items grid-gallery\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9812\" role=\"button\" tabindex=\"0\" rel=\"jtg-9792\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9812\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer.jpg\" title=\"camisas columbia blanca manga larga mujer\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-mujer-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia blanca manga larga mujer<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9810\" role=\"button\" tabindex=\"0\" rel=\"jtg-9792\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9810\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal.jpg\" title=\"camisas columbia blanca manga corta normal\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal.jpg 400w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-corta-normal-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia blanca manga corta normal<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9811\" role=\"button\" tabindex=\"0\" rel=\"jtg-9792\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9811\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales.jpg\" title=\"camisas columbia blanca manga larga bolsillos diagonales\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-larga-bolsillos-diagonales-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia blanca manga larga bolsillos diagonales<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9809\" role=\"button\" tabindex=\"0\" rel=\"jtg-9792\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9809\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales.jpg\" title=\"camisas columbia blanca manga bolsillos normales\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales.jpg 500w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-columbia-blanca-manga-bolsillos-normales-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisas columbia blanca manga bolsillos normales<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"http:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\",\n\t\t\"url\"     : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n<hr>\n<style>#jtg-9796 .modula-item { border: 3px solid #aaaaaa; }#jtg-9796 .modula-item { border-radius: 5px; }#jtg-9796 .modula-item { box-shadow: #aaaaaa 0px 0px 3px; }#jtg-9796 .modula-item .jtg-social a, .lightbox-socials.jtg-social a{ fill: #ffffff; color: #ffffff }#jtg-9796 .modula-item .jtg-social-expandable a, #jtg-9796 .modula-item .jtg-social-expandable-icons a{ fill: #ffffff; color: #ffffff }#jtg-9796 .modula-item .jtg-social svg, .lightbox-socials.jtg-social svg { height: 16px; width: 16px }#jtg-9796 .modula-item .jtg-social-expandable svg { height: 16px; width: 16px }#jtg-9796 .modula-item .jtg-social-expandable-icons svg { height: 16px; width: 16px }#jtg-9796 .modula-item .jtg-social a:not(:last-child), .lightbox-socials.jtg-social a:not(:last-child) { margin-right: 10px }#jtg-9796 .modula-item .jtg-social-expandable-icons { gap: 10px }#jtg-9796 .modula-item .figc {color:#ffffff;}#jtg-9796 .modula-item .modula-item-content { transform: scale(1); }#jtg-9796 { width:100%;}#jtg-9796 .modula-items .figc p.description { font-size:14px; }#jtg-9796 .modula-items .figc p.description { color:#ffffff;}#jtg-9796.modula-gallery .modula-item > a, #jtg-9796.modula-gallery .modula-item, #jtg-9796.modula-gallery .modula-item-content > a:not(.modula-no-follow) { cursor:zoom-in; } #jtg-9796.modula-gallery .modula-item-content .modula-no-follow { cursor: default; } #jtg-9796.modula-gallery .modula-item, #jtg-9796.modula-gallery .modula-grid-sizer { width: calc(25% - 7.5px) ; } @media (min-width: 768px) and (max-width:992px) { html body #jtg-9796.modula-gallery .modula-item, html body  #jtg-9796.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }@media (max-width: 768px) { html body #jtg-9796.modula-gallery .modula-item, html body  #jtg-9796.modula-gallery .modula-grid-sizer {width: calc(25% - 7.5px ) ; } }#jtg-9796 .modula-items{position:relative;}@media screen and (max-width:480px){#jtg-9796 .modula-item .figc .jtg-title {  font-size: 12px; }#jtg-9796 .modula-items .figc p.description { color:#ffffff;font-size:10px; }}<\/style>\n<div  id=\"jtg-9796\" class=\"modula modula-gallery modula-columns\" data-config=\"{&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:&quot;2&quot;,&quot;mobileColumns&quot;:&quot;1&quot;,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:false},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-9796&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;grid_type&quot;:&quot;4&quot;,&quot;rowHeight&quot;:150,&quot;lastRow&quot;:&quot;justify&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t<div class=\"modula-grid-sizer\"> <\/div>\n\t<div  class=\"modula-items grid-gallery\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9827\" role=\"button\" tabindex=\"0\" rel=\"jtg-9796\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9827\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera.jpg\" title=\"camisa columbia negra manga bolsillos diagonales entera\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-bolsillos-diagonales-entera-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisa columbia negra manga bolsillos diagonales entera<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9829\" role=\"button\" tabindex=\"0\" rel=\"jtg-9796\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9829\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer.jpg\" title=\"camisa columbia negra manga larga para mujer\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-para-mujer-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisa columbia negra manga larga para mujer<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9826\" role=\"button\" tabindex=\"0\" rel=\"jtg-9796\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9826\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra.jpg\" title=\"camisa columbia negra\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra.jpg 400w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-300x300_c.jpg 300w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-330x330.jpg 330w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisa columbia negra<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a data-image-id=\"9828\" role=\"button\" tabindex=\"0\" rel=\"jtg-9796\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-9828\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales.jpg\" title=\"camisa columbia negra manga larga con bolsillos diagonales\" width=\"300\" height=\"300\" src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-300x300_c.jpg\" data-src=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-300x300_c.jpg\" data-caption=\"\" srcset=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-150x150.jpg 150w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-230x230.jpg 230w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-330x330.jpg 330w, https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisa-columbia-negra-manga-larga-con-bolsillos-diagonales-300x300_c.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t<div class='jtg-title'>camisa columbia negra manga larga con bolsillos diagonales<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"http:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\",\n\t\t\"url\"     : \"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n<hr>\n<h2>Utilidad de las camisas tipo columbia para empresas<\/h2>\n<p>Adem\u00e1s de que las mismas son frescas, transpirables y dem\u00e1s, estas camisas son bastante \u00fatiles a la hora de trabajar con herramientas. Si el trabajo de su personal depende de tener herramientas siempre a mano, estas camisas son una buena opci\u00f3n, ya que estas cuentan con m\u00faltiples bolsillos para que la persona que la porta pueda echar cualquier cosa que ocupe poco espacio. Y no tiene que limitarse a la cantidad de bolsillos que traen las camisas columbia originales, porque pueden ser m\u00e1s.<\/p>\n<p><a href=\"https:\/\/cstradha.xyz\/do\/contactenos\/\">Cont\u00e1ctenos<\/a> para adquirir nuestros productos, o recibir una cotizaci\u00f3n.<\/p>\n<hr>\n","protected":false},"excerpt":{"rendered":"<p>Camisas tipo columbia para empresas La comodidad de sus empleados a la hora de trabajar, en especial en ambientes que son muy calurosos e inc\u00f3modos para ejercer las labores, es muy importante, ya que en primer lugar, pensar en la<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-9851","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha<\/title>\n<meta name=\"description\" content=\"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha\" \/>\n<meta property=\"og:description\" content=\"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Confecciones cstradha, Santo Domingo, RD\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/cstradha\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-10T20:25:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\",\"url\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\",\"name\":\"Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha\",\"isPartOf\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\",\"datePublished\":\"2021-03-23T13:03:29+00:00\",\"dateModified\":\"2025-01-10T20:25:53+00:00\",\"description\":\"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.\",\"breadcrumb\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage\",\"url\":\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\",\"contentUrl\":\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png\",\"width\":1280,\"height\":331,\"caption\":\"camisas tipo columbia para empresas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Santo Domingo (RD)\",\"item\":\"https:\/\/cstradha.xyz\/do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camisas tipo columbia para empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cstradha.xyz\/do\/#website\",\"url\":\"https:\/\/cstradha.xyz\/do\/\",\"name\":\"Confecciones cstradha, Santo Domingo, RD\",\"description\":\"Confeccion de todo tipo de indumentarias.\",\"publisher\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cstradha.xyz\/do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cstradha.xyz\/do\/#organization\",\"name\":\"cstradha\",\"url\":\"https:\/\/cstradha.xyz\/do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cstradha.xyz\/do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2024\/10\/weblogo-actualizado-2024-1.png\",\"contentUrl\":\"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2024\/10\/weblogo-actualizado-2024-1.png\",\"width\":627,\"height\":142,\"caption\":\"cstradha\"},\"image\":{\"@id\":\"https:\/\/cstradha.xyz\/do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/cstradha\",\"http:\/\/instagram.com\/cstradha\",\"http:\/\/pinterest.com\/cstradha\",\"https:\/\/www.youtube.com\/channel\/UCrwbM4STuW2H7UhStKqveSg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha","description":"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/","og_locale":"es_ES","og_type":"article","og_title":"Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha","og_description":"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.","og_url":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/","og_site_name":"Confecciones cstradha, Santo Domingo, RD","article_publisher":"http:\/\/facebook.com\/cstradha","article_modified_time":"2025-01-10T20:25:53+00:00","og_image":[{"url":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/","url":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/","name":"Camisas tipo columbia para empresas en Santo Domingo, RD - cstradha","isPartOf":{"@id":"https:\/\/cstradha.xyz\/do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage"},"image":{"@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png","datePublished":"2021-03-23T13:03:29+00:00","dateModified":"2025-01-10T20:25:53+00:00","description":"Busca camisas tipo columbia para empresas, que sean c\u00f3modas, que est\u00e9n fabricadas en telas resistentes? Escr\u00edbanos al (829) 694-3467.","breadcrumb":{"@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#primaryimage","url":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png","contentUrl":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2021\/03\/camisas-tipo-columbia-para-empresas.png","width":1280,"height":331,"caption":"camisas tipo columbia para empresas"},{"@type":"BreadcrumbList","@id":"https:\/\/cstradha.xyz\/do\/camisas-tipo-columbia-para-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Santo Domingo (RD)","item":"https:\/\/cstradha.xyz\/do\/"},{"@type":"ListItem","position":2,"name":"Camisas tipo columbia para empresas"}]},{"@type":"WebSite","@id":"https:\/\/cstradha.xyz\/do\/#website","url":"https:\/\/cstradha.xyz\/do\/","name":"Confecciones cstradha, Santo Domingo, RD","description":"Confeccion de todo tipo de indumentarias.","publisher":{"@id":"https:\/\/cstradha.xyz\/do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cstradha.xyz\/do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cstradha.xyz\/do\/#organization","name":"cstradha","url":"https:\/\/cstradha.xyz\/do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cstradha.xyz\/do\/#\/schema\/logo\/image\/","url":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2024\/10\/weblogo-actualizado-2024-1.png","contentUrl":"https:\/\/cstradha.xyz\/do\/wp-content\/uploads\/sites\/2\/2024\/10\/weblogo-actualizado-2024-1.png","width":627,"height":142,"caption":"cstradha"},"image":{"@id":"https:\/\/cstradha.xyz\/do\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/cstradha","http:\/\/instagram.com\/cstradha","http:\/\/pinterest.com\/cstradha","https:\/\/www.youtube.com\/channel\/UCrwbM4STuW2H7UhStKqveSg"]}]}},"_links":{"self":[{"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/pages\/9851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/comments?post=9851"}],"version-history":[{"count":4,"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/pages\/9851\/revisions"}],"predecessor-version":[{"id":9857,"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/pages\/9851\/revisions\/9857"}],"wp:attachment":[{"href":"https:\/\/cstradha.xyz\/do\/wp-json\/wp\/v2\/media?parent=9851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}